{"id":23,"date":"2017-10-07T13:07:37","date_gmt":"2017-10-07T11:07:37","guid":{"rendered":"https:\/\/solidparkiet.pl\/sp17\/?page_id=23"},"modified":"2020-10-27T07:52:23","modified_gmt":"2020-10-27T06:52:23","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/www.solidparkiet.pl\/de\/kontakt\/","title":{"rendered":"Kontakt"},"content":{"rendered":"<p><span style=\"color: #000000;\"><strong><span style=\"font-size: 18pt;\">Solid-Parkiet s.c.<\/span><\/strong><\/span>[\/vc_column_text][vc_empty_space height=\u201e15px\u201c]<\/p><div class=\"q_icon_with_title tiny normal_icon left_from_title \"><div class=\"icon_text_holder\" style><div class=\"icon_text_inner\" style><div class=\"icon_title_holder\"><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\" style=\"font-size: 15px;\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-lg  \"><i class=\"qode_icon_font_awesome fa fa-map-marker qode_iwt_icon_element\" style=\"color: #000000;\"><\/i><\/span><\/div><h6 class=\"icon_title\" style=\"color: #000000;\">32 \u2013 830 Wojnicz, ul. Wolicka 7,&nbsp;PL<\/h6><\/div><p style><\/p><\/div><\/div><\/div>[vc_empty_space height=\u201e25px\u201c][vc_column_text]<strong><span style=\"font-family: verdana, geneva, sans-serif;\">Sekretariat \/ Verkauf<\/span><\/strong>[\/vc_column_text][vc_empty_space height=\u201e12px\u201c][vc_column_text]<strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 10pt;\">Polnisch<\/span><\/strong>[\/vc_column_text][vc_empty_space height=\u201e8px\u201c]<div class=\"q_icon_with_title tiny normal_icon left_from_title \"><div class=\"icon_text_holder\" style><div class=\"icon_text_inner\" style><div class=\"icon_title_holder\"><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\" style=\"font-size: 15px;\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-lg  \"><i class=\"qode_icon_font_awesome fa fa-phone qode_iwt_icon_element\" style=\"color: #000000;\"><\/i><\/span><\/div><h6 class=\"icon_title\" style=\"color: #000000;\">+48 14 67 87&nbsp;500<\/h6><\/div><p style><\/p><\/div><\/div><\/div><div class=\"q_icon_with_title tiny normal_icon left_from_title \"><div class=\"icon_text_holder\" style><div class=\"icon_text_inner\" style><div class=\"icon_title_holder\"><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\" style=\"font-size: 15px;\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-lg  \"><i class=\"qode_icon_font_awesome fa fa-fax qode_iwt_icon_element\" style=\"color: #000000;\"><\/i><\/span><\/div><h6 class=\"icon_title\" style=\"color: #000000;\">+48 14 67 87&nbsp;501<\/h6><\/div><p style><\/p><\/div><\/div><\/div><div class=\"q_icon_with_title tiny normal_icon left_from_title \"><div class=\"icon_text_holder\" style><div class=\"icon_text_inner\" style><div class=\"icon_title_holder\"><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\" style=\"font-size: 15px;\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-lg  \"><i class=\"qode_icon_font_awesome fa fa-envelope qode_iwt_icon_element\" style=\"color: #000000;\"><\/i><\/span><\/div><h6 class=\"icon_title\" style=\"color: #000000;\">biuro@solidparkiet.pl<\/h6><\/div><p style><\/p><\/div><\/div><\/div>[vc_empty_space height=\u201e25px\u201c][vc_column_text]<strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 10pt;\">Deutsch \/ Englisch<\/span><\/strong>[\/vc_column_text][vc_empty_space height=\u201e8px\u201c]<div class=\"q_icon_with_title tiny normal_icon left_from_title \"><div class=\"icon_text_holder\" style><div class=\"icon_text_inner\" style><div class=\"icon_title_holder\"><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\" style=\"font-size: 15px;\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-lg  \"><i class=\"qode_icon_font_awesome fa fa-phone qode_iwt_icon_element\" style=\"color: #000000;\"><\/i><\/span><\/div><h6 class=\"icon_title\" style=\"color: #000000;\">+48 506 300&nbsp;670<\/h6><\/div><p style><\/p><\/div><\/div><\/div><div class=\"q_icon_with_title tiny normal_icon left_from_title \"><div class=\"icon_text_holder\" style><div class=\"icon_text_inner\" style><div class=\"icon_title_holder\"><div class=\"icon_holder \" style=\" \"><span data-icon-type=\"normal\" style=\"font-size: 15px;\" class=\"qode_iwt_icon_holder q_font_awsome_icon fa-lg  \"><i class=\"qode_icon_font_awesome fa fa-envelope qode_iwt_icon_element\" style=\"color: #000000;\"><\/i><\/span><\/div><h6 class=\"icon_title\" style=\"color: #000000;\">office@solidparkiet.pl<\/h6><\/div><p style><\/p><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row css_animation=\u201c\u201c row_type=\u201erow\u201c use_row_as_full_screen_section=\u201eno\u201c type=\u201efull_width\u201c angled_section=\u201eno\u201c text_align=\u201eleft\u201c background_image_as_pattern=\u201ewithout_pattern\u201c padding_top=\u201e10\u201c padding_bottom=\u201e45\u201c][vc_column]<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f22-o1\" lang=\"de-DE\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/23#wpcf7-f22-o1\" method=\"post\" class=\"wpcf7-form cf7_custom_style_3\" novalidate=\"novalidate\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"22\">\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.1.7\">\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\">\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f22-o1\">\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\">\n<input type=\"hidden\" name=\"g-recaptcha-response\" value>\n<\/div>\n<div class=\"one-half\">\n<label> Vorname*<br>\n    <span class=\"wpcf7-form-control-wrap vorname\"><input type=\"text\" name=\"vorname\" value size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><\/span> <\/label>\n<\/div>\n<div class=\"one-half last\">\n<label> Nachname*<br>\n    <span class=\"wpcf7-form-control-wrap nachname\"><input type=\"text\" name=\"nachname\" value size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><\/span> <\/label>\n<\/div>\n<div class=\"one-half\">\n<label> Ihre E\u2011Mail-Adresse*<br>\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\"><\/span> <\/label>\n<\/div>\n<div class=\"one-half last\">\n<label> Stadt*<br>\n    <span class=\"wpcf7-form-control-wrap stadt\"><input type=\"text\" name=\"stadt\" value size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><\/span> <\/label>\n<\/div>\n<div class=\"one-half\">\n<label> Land<br>\n<span class=\"wpcf7-form-control-wrap your-country\"><select name=\"your-country\" class=\"wpcf7-form-control wpcf7-select\" aria-invalid=\"false\"><option value>---<\/option><option value=\"Austria\">Austria<\/option><option value=\"Belgium\">Belgium<\/option><option value=\"Germany\">Germany<\/option><option value=\"Liechtenstein\">Liechtenstein<\/option><option value=\"Luxembourg\">Luxembourg<\/option><option value=\"Switzerland\">Switzerland<\/option><option value><\/option><option value=\"Belarus\">Belarus<\/option><option value=\"Bosnia and Herzegovina\">Bosnia and Herzegovina<\/option><option value=\"Bulgaria\">Bulgaria<\/option><option value=\"Canada\">Canada<\/option><option value=\"Croatia\">Croatia<\/option><option value=\"Czech Republic\">Czech Republic<\/option><option value=\"Denmark\">Denmark<\/option><option value=\"Estonia\">Estonia<\/option><option value=\"Finland\">Finland<\/option><option value=\"France\">France<\/option><option value=\"Georgia\">Georgia<\/option><option value=\"Greece\">Greece<\/option><option value=\"Hungary\">Hungary<\/option><option value=\"Iceland\">Iceland<\/option><option value=\"Ireland\">Ireland<\/option><option value=\"Italy\">Italy<\/option><option value=\"Latvia\">Latvia<\/option><option value=\"Lithuania\">Lithuania<\/option><option value=\"Malta\">Malta<\/option><option value=\"Monaco\">Monaco<\/option><option value=\"Netherlands\">Netherlands<\/option><option value=\"New Zealand\">New Zealand<\/option><option value=\"Norway\">Norway<\/option><option value=\"Poland\">Poland<\/option><option value=\"Portugal\">Portugal<\/option><option value=\"Romania\">Romania<\/option><option value=\"Russian Federation\">Russian Federation<\/option><option value=\"Saudi Arabia\">Saudi Arabia<\/option><option value=\"Serbia\">Serbia<\/option><option value=\"Slovakia\">Slovakia<\/option><option value=\"Slovenia\">Slovenia<\/option><option value=\"Spain\">Spain<\/option><option value=\"Sweden\">Sweden<\/option><option value=\"Turkey\">Turkey<\/option><option value=\"Ukraine\">Ukraine<\/option><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"United States\">United States<\/option><\/select><\/span> <\/label>\n<\/div>\n<div class=\"one-half last\">\n<label> Betreff*<br>\n    <span class=\"wpcf7-form-control-wrap your-subject\"><input type=\"text\" name=\"your-subject\" value size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><\/span> <\/label>\n<\/div>\n<p><label> Ihre Nachricht*<br>\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<p><input type=\"submit\" value=\"Senden\" class=\"wpcf7-form-control wpcf7-submit\"><\/p>\n<input type=\"hidden\" class=\"wpcf7-pum\" value=\"{&quot;closepopup&quot;:false,&quot;closedelay&quot;:0,&quot;openpopup&quot;:false,&quot;openpopup_id&quot;:0}\"><div class=\"wpcf7-response-output wpcf7-display-none\"><\/div><\/form><\/div>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>Solid-Parkiet s.c.[\/vc_column_text][vc_empty_space height=\u201e15px\u201c][vc_empty_space height=\u201e25px\u201c][vc_column_text]Sekretariat \/ Verkauf[\/vc_column_text][vc_empty_space height=\u201e12px\u201c][vc_column_text]Polnisch[\/vc_column_text][vc_empty_space height=\u201e8px\u201c][vc_empty_space height=\u201e25px\u201c][vc_column_text]Deutsch \/ Englisch[\/vc_column_text][vc_empty_space height=\u201e8px\u201c][\/vc_column][\/vc_row][vc_row css_animation=\u201c\u201c row_type=\u201erow\u201c use_row_as_full_screen_section=\u201eno\u201c type=\u201efull_width\u201c angled_section=\u201eno\u201c text_align=\u201eleft\u201c background_image_as_pattern=\u201ewithout_pattern\u201c padding_top=\u201e10\u201c padding_bottom=\u201e45\u201c][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"wp_typography_post_enhancements_disabled":false},"_links":{"self":[{"href":"https:\/\/www.solidparkiet.pl\/de\/wp-json\/wp\/v2\/pages\/23"}],"collection":[{"href":"https:\/\/www.solidparkiet.pl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.solidparkiet.pl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.solidparkiet.pl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solidparkiet.pl\/de\/wp-json\/wp\/v2\/comments?post=23"}],"version-history":[{"count":30,"href":"https:\/\/www.solidparkiet.pl\/de\/wp-json\/wp\/v2\/pages\/23\/revisions"}],"predecessor-version":[{"id":6421,"href":"https:\/\/www.solidparkiet.pl\/de\/wp-json\/wp\/v2\/pages\/23\/revisions\/6421"}],"wp:attachment":[{"href":"https:\/\/www.solidparkiet.pl\/de\/wp-json\/wp\/v2\/media?parent=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}